{"id":22521,"date":"2024-07-24T16:07:23","date_gmt":"2024-07-24T16:07:23","guid":{"rendered":"https:\/\/madisonsresto.com\/?page_id=22521"},"modified":"2025-09-25T18:32:00","modified_gmt":"2025-09-25T18:32:00","slug":"kids-menu","status":"publish","type":"page","link":"https:\/\/madisonsresto.com\/en\/kids-menu\/","title":{"rendered":"Kids Menu"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"22521\" class=\"elementor elementor-22521 elementor-20343\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e87d6a elementor-hidden-desktop elementor-hidden-laptop e-flex e-con-boxed e-con e-parent\" data-id=\"4e87d6a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25d94c5 elementor-widget__width-auto elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget-tablet__width-auto elementor-widget elementor-widget-button\" data-id=\"25d94c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/main-menu\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"21\" viewBox=\"0 0 20 21\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0.673828 0.5C0.949971 0.5 1.17383 0.723858 1.17383 1L1.17383 19.667C1.17383 19.9431 0.94997 20.167 0.673828 20.167C0.397686 20.167 0.173828 19.9431 0.173828 19.667L0.173829 1C0.173829 0.723858 0.397687 0.5 0.673828 0.5ZM10.8064 3.31345C11.0016 3.50871 11.0016 3.82529 10.8064 4.02055L4.99294 9.834L19.3218 9.834C19.598 9.834 19.8218 10.0579 19.8218 10.334C19.8218 10.6101 19.598 10.834 19.3218 10.834L4.99306 10.834L10.8064 16.6464C11.0016 16.8417 11.0017 17.1583 10.8064 17.3535C10.6112 17.5488 10.2946 17.5488 10.0993 17.3536L3.4323 10.6876C3.33852 10.5938 3.28584 10.4666 3.28583 10.334C3.28583 10.2014 3.3385 10.0742 3.43228 9.98045L10.0993 3.31345C10.2945 3.11818 10.6111 3.11818 10.8064 3.31345Z\" fill=\"#E8DED3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Return to main menu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fde56fc elementor-hidden-desktop elementor-hidden-laptop e-flex e-con-boxed e-con e-parent\" data-id=\"fde56fc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<nav class=\"elementor-element elementor-element-3f3603d e-con-full e-flex e-con e-child\" data-id=\"3f3603d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e9b87b elementor-widget__width-auto elementor-widget elementor-widget-n-accordion\" data-id=\"1e9b87b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3200\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3200\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Kids Menu <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3200\" class=\"elementor-element elementor-element-17d3146 e-con-full e-flex e-con e-child\" data-id=\"17d3146\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3200\" class=\"elementor-element elementor-element-40fae29 e-con-full e-flex e-con e-child\" data-id=\"40fae29\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3526aac elementor-nav-menu__align-start elementor-nav-menu--dropdown-none elementor-widget-mobile__width-inherit elementor-widget elementor-widget-nav-menu\" data-id=\"3526aac\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-3526aac\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-22583\"><a href=\"https:\/\/madisonsresto.com\/en\/main-menu\/\" class=\"elementor-item\">Main Menu<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-22586\"><a href=\"https:\/\/madisonsresto.com\/en\/dessert-menu\/\" class=\"elementor-item\">Dessert Menu<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-22587\"><a href=\"https:\/\/madisonsresto.com\/en\/bar-menu\/\" class=\"elementor-item\">Bar Menu<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-22588\"><a href=\"https:\/\/madisonsresto.com\/en\/wine-menu-en\/\" class=\"elementor-item\">Wine Menu<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-22585\"><a href=\"https:\/\/madisonsresto.com\/en\/kids-menu\/\" class=\"elementor-item\">Kids Menu<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-3526aac\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-22583\"><a href=\"https:\/\/madisonsresto.com\/en\/main-menu\/\" class=\"elementor-item\" tabindex=\"-1\">Main Menu<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-22586\"><a href=\"https:\/\/madisonsresto.com\/en\/dessert-menu\/\" class=\"elementor-item\" tabindex=\"-1\">Dessert Menu<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-22587\"><a href=\"https:\/\/madisonsresto.com\/en\/bar-menu\/\" class=\"elementor-item\" tabindex=\"-1\">Bar Menu<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-22588\"><a href=\"https:\/\/madisonsresto.com\/en\/wine-menu-en\/\" class=\"elementor-item\" tabindex=\"-1\">Wine Menu<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-22585\"><a href=\"https:\/\/madisonsresto.com\/en\/kids-menu\/\" class=\"elementor-item\" tabindex=\"-1\">Kids Menu<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/nav>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f078ca8 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"f078ca8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:55,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-012f9b3 elementor-widget__width-auto elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"012f9b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/main-menu\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"21\" viewBox=\"0 0 20 21\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0.673828 0.5C0.949971 0.5 1.17383 0.723858 1.17383 1L1.17383 19.667C1.17383 19.9431 0.94997 20.167 0.673828 20.167C0.397686 20.167 0.173828 19.9431 0.173828 19.667L0.173829 1C0.173829 0.723858 0.397687 0.5 0.673828 0.5ZM10.8064 3.31345C11.0016 3.50871 11.0016 3.82529 10.8064 4.02055L4.99294 9.834L19.3218 9.834C19.598 9.834 19.8218 10.0579 19.8218 10.334C19.8218 10.6101 19.598 10.834 19.3218 10.834L4.99306 10.834L10.8064 16.6464C11.0016 16.8417 11.0017 17.1583 10.8064 17.3535C10.6112 17.5488 10.2946 17.5488 10.0993 17.3536L3.4323 10.6876C3.33852 10.5938 3.28584 10.4666 3.28583 10.334C3.28583 10.2014 3.3385 10.0742 3.43228 9.98045L10.0993 3.31345C10.2945 3.11818 10.6111 3.11818 10.8064 3.31345Z\" fill=\"#E8DED3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Go back<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d9a02 elementor-widget__width-auto elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"e3d9a02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/dessert-menu\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.77776 0.359443C3.92341 0.286011 4.09572 0.288238 4.23942 0.365411L17.2366 7.34537C17.3988 7.43249 17.5 7.60173 17.5 7.78587V17.1931C17.5 17.4692 17.2761 17.6931 17 17.6931H4C2.067 17.6931 0.5 16.1261 0.5 14.1931V7.78587C0.5 3.26355 2.57583 0.965432 3.77776 0.359443ZM1.50922 7.28587H15.0122L4.01424 1.37956C3.16865 1.95174 1.64163 3.73646 1.50922 7.28587ZM16.5 8.28587H1.5V14.1931C1.5 15.5738 2.61929 16.6931 4 16.6931H16.5V8.28587Z\" fill=\"#E8DED3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Dessert Menu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b04d6d elementor-widget__width-auto elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"8b04d6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/lunch-menu\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"20\" viewBox=\"0 0 16 20\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0.726562 0.580078C1.0027 0.580078 1.22656 0.803936 1.22656 1.08008V4.9079C1.22656 6.26588 2.32742 7.36673 3.68539 7.36673C5.04336 7.36673 6.14422 6.26588 6.14422 4.9079V1.08008C6.14422 0.803936 6.36808 0.580078 6.64422 0.580078C6.92036 0.580078 7.14422 0.803936 7.14422 1.08008V4.9079C7.14422 6.64836 5.85872 8.08857 4.18539 8.33086V18.9198C4.18539 19.1959 3.96153 19.4198 3.68539 19.4198C3.40925 19.4198 3.18539 19.1959 3.18539 18.9198V8.33086C1.51206 8.08857 0.226562 6.64836 0.226562 4.9079V1.08008C0.226562 0.803936 0.45042 0.580078 0.726562 0.580078ZM3.65612 0.580078C3.93226 0.580078 4.15612 0.803936 4.15612 1.08008V5.07437C4.15612 5.35051 3.93226 5.57437 3.65612 5.57437C3.37998 5.57437 3.15612 5.35051 3.15612 5.07437V1.08008C3.15612 0.803936 3.37998 0.580078 3.65612 0.580078ZM15.627 0.726525C15.7208 0.820293 15.7734 0.94747 15.7734 1.08008L15.7734 18.9198C15.7734 19.1959 15.5496 19.4198 15.2734 19.4198C14.9973 19.4198 14.7734 19.1959 14.7734 18.9198L14.7734 1.67139C14.7496 1.67823 14.7251 1.68557 14.7 1.69345C14.3277 1.81044 13.8181 2.04822 13.3018 2.53488C12.2776 3.50038 11.1443 5.52884 11.1443 9.80787V13.498H12.7676C13.0437 13.498 13.2676 13.7219 13.2676 13.998C13.2676 14.2742 13.0437 14.498 12.7676 14.498H10.6443C10.3681 14.498 10.1443 14.2742 10.1443 13.998V9.80787C10.1443 5.35911 11.3255 3.02367 12.6159 1.80723C13.2569 1.20291 13.9046 0.895199 14.4002 0.739446C14.6474 0.661766 14.8564 0.621986 15.0078 0.601598C15.0835 0.591396 15.1451 0.586021 15.1901 0.583193C15.2126 0.581779 15.231 0.581001 15.245 0.580575L15.2626 0.580167L15.2689 0.580096L15.2714 0.580082L15.2725 0.580079C15.273 0.580078 15.2734 0.580078 15.2734 1.08008V0.580078C15.406 0.580078 15.5332 0.632757 15.627 0.726525Z\" fill=\"#E8DED3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lunch Menu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1e7e37 elementor-widget__width-auto elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"d1e7e37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/bar-menu\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"20\" viewBox=\"0 0 18 20\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.1058 0.638895C15.3374 0.78935 15.4031 1.09903 15.2526 1.33059L13.8215 3.53314C13.6711 3.7647 13.3614 3.83044 13.1298 3.67999C12.8983 3.52953 12.8325 3.21985 12.983 2.9883L14.4141 0.785742C14.5646 0.554186 14.8742 0.488441 15.1058 0.638895ZM4.12461 2.65764C2.62222 2.65764 1.4043 3.87556 1.4043 5.37795C1.4043 6.43269 2.00445 7.34811 2.88421 7.79977C3.12987 7.92589 3.22677 8.22728 3.10065 8.47294C2.97453 8.7186 2.67315 8.8155 2.42749 8.68938C1.22726 8.07319 0.404297 6.82211 0.404297 5.37795C0.404297 3.32328 2.06994 1.65764 4.12461 1.65764C5.23698 1.65764 6.23579 2.14646 6.9168 2.91935C7.09936 3.12654 7.07939 3.44249 6.8722 3.62505C6.66501 3.80761 6.34906 3.78764 6.1665 3.58045C5.66727 3.01387 4.93785 2.65764 4.12461 2.65764ZM3.6679 5.81946C3.74886 5.64057 3.92705 5.52563 4.12341 5.52563H17.0939C17.2903 5.52563 17.4685 5.64057 17.5494 5.81946C17.6304 5.99835 17.5991 6.20808 17.4695 6.35561L11.1087 13.5967V18.4454H13.8513C14.1274 18.4454 14.3513 18.6692 14.3513 18.9454C14.3513 19.2215 14.1274 19.4454 13.8513 19.4454H7.36604C7.08989 19.4454 6.86604 19.2215 6.86604 18.9454C6.86604 18.6692 7.08989 18.4454 7.36604 18.4454H10.1087V13.5967L3.74777 6.35561C3.61817 6.20808 3.58693 5.99835 3.6679 5.81946ZM10.6087 12.6507L15.9892 6.52563H5.22815L10.6087 12.6507Z\" fill=\"#E8DED3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Bar Menu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32de20d elementor-widget__width-auto elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"32de20d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/wine-menu\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"20\" viewBox=\"0 0 18 20\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.1058 0.638895C15.3374 0.78935 15.4031 1.09903 15.2526 1.33059L13.8215 3.53314C13.6711 3.7647 13.3614 3.83044 13.1298 3.67999C12.8983 3.52953 12.8325 3.21985 12.983 2.9883L14.4141 0.785742C14.5646 0.554186 14.8742 0.488441 15.1058 0.638895ZM4.12461 2.65764C2.62222 2.65764 1.4043 3.87556 1.4043 5.37795C1.4043 6.43269 2.00445 7.34811 2.88421 7.79977C3.12987 7.92589 3.22677 8.22728 3.10065 8.47294C2.97453 8.7186 2.67315 8.8155 2.42749 8.68938C1.22726 8.07319 0.404297 6.82211 0.404297 5.37795C0.404297 3.32328 2.06994 1.65764 4.12461 1.65764C5.23698 1.65764 6.23579 2.14646 6.9168 2.91935C7.09936 3.12654 7.07939 3.44249 6.8722 3.62505C6.66501 3.80761 6.34906 3.78764 6.1665 3.58045C5.66727 3.01387 4.93785 2.65764 4.12461 2.65764ZM3.6679 5.81946C3.74886 5.64057 3.92705 5.52563 4.12341 5.52563H17.0939C17.2903 5.52563 17.4685 5.64057 17.5494 5.81946C17.6304 5.99835 17.5991 6.20808 17.4695 6.35561L11.1087 13.5967V18.4454H13.8513C14.1274 18.4454 14.3513 18.6692 14.3513 18.9454C14.3513 19.2215 14.1274 19.4454 13.8513 19.4454H7.36604C7.08989 19.4454 6.86604 19.2215 6.86604 18.9454C6.86604 18.6692 7.08989 18.4454 7.36604 18.4454H10.1087V13.5967L3.74777 6.35561C3.61817 6.20808 3.58693 5.99835 3.6679 5.81946ZM10.6087 12.6507L15.9892 6.52563H5.22815L10.6087 12.6507Z\" fill=\"#E8DED3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Wine Menu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4543e34 elementor-widget__width-auto elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"4543e34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/kids-menu\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M5.2827 1.5C2.91743 1.5 1 3.41743 1 5.7827C1 6.18884 1.12671 6.83535 1.37701 7.6539C1.62361 8.46034 1.97793 9.39509 2.4049 10.3617C3.26172 12.3015 4.39216 14.327 5.49418 15.6792C5.70392 15.9365 5.89631 16.043 6.04573 16.0787C6.1914 16.1135 6.34523 16.0932 6.50887 16.005C6.85565 15.8182 7.22122 15.3292 7.37941 14.611C7.69203 13.1917 9.64781 13.1917 9.96043 14.611C10.1186 15.3292 10.4842 15.8182 10.831 16.005C10.9946 16.0932 11.1484 16.1135 11.2941 16.0787C11.4435 16.043 11.6359 15.9365 11.8457 15.6792C12.9477 14.327 14.0781 12.3015 14.9349 10.3617C15.3619 9.39509 15.7162 8.46034 15.9628 7.6539C16.2131 6.83535 16.3398 6.18884 16.3398 5.7827C16.3398 3.41743 14.4224 1.5 12.0571 1.5C10.8719 1.5 9.79997 1.98078 9.02403 2.75916C8.93022 2.85327 8.8028 2.90617 8.66992 2.90617C8.53704 2.90617 8.40963 2.85327 8.31581 2.75916C7.53987 1.98078 6.4679 1.5 5.2827 1.5ZM0 5.7827C0 2.86515 2.36515 0.5 5.2827 0.5C6.57153 0.5 7.75318 0.962053 8.66992 1.72872C9.58667 0.962053 10.7683 0.5 12.0571 0.5C14.9747 0.5 17.3398 2.86515 17.3398 5.7827C17.3398 6.34306 17.176 7.10634 16.9191 7.94632C16.6586 8.79841 16.2891 9.77093 15.8497 10.7658C14.9737 12.7489 13.8009 14.8631 12.6208 16.311C12.3072 16.6958 11.9373 16.9531 11.5266 17.0513C11.1121 17.1504 10.7079 17.0746 10.3567 16.8854C9.67366 16.5174 9.18205 15.726 8.98384 14.8261C8.93869 14.6212 8.80147 14.5465 8.66992 14.5465C8.53837 14.5465 8.40115 14.6212 8.356 14.8261C8.1578 15.726 7.66618 16.5174 6.98318 16.8854C6.63194 17.0746 6.22774 17.1504 5.81326 17.0513C5.40253 16.9531 5.03264 16.6958 4.71901 16.311C3.53898 14.8631 2.36612 12.7489 1.49016 10.7658C1.05073 9.77093 0.681284 8.79841 0.420722 7.94632C0.163862 7.10634 0 6.34306 0 5.7827ZM12.3115 3.90707C12.507 3.71212 12.8236 3.71261 13.0186 3.90818C13.3013 4.19177 13.5759 4.49121 13.7684 4.89773C13.9631 5.30881 14.0556 5.78825 14.0556 6.41728C14.0556 7.12057 13.7374 7.90084 13.4623 8.45611C13.3195 8.74434 13.1772 8.99344 13.0706 9.17056C13.0171 9.25935 12.9723 9.33062 12.9404 9.38031C12.9245 9.40518 12.9118 9.42468 12.9028 9.43832L12.8922 9.45433L12.8891 9.45893L12.8881 9.46036C12.8881 9.46044 12.8876 9.4612 12.473 9.18164L12.8876 9.4612C12.7332 9.69015 12.4224 9.75058 12.1935 9.59619C11.9646 9.44183 11.9041 9.13116 12.0584 8.90222L12.0601 8.89967L12.0676 8.88834C12.0745 8.8779 12.085 8.86179 12.0987 8.84049C12.126 8.79787 12.1657 8.73468 12.2138 8.65486C12.3101 8.49477 12.4385 8.27011 12.5663 8.01214C12.8324 7.475 13.0556 6.87309 13.0556 6.41728C13.0556 5.88723 12.9778 5.56481 12.8646 5.32571C12.7492 5.08205 12.5783 4.88299 12.3104 4.61418C12.1154 4.41861 12.1159 4.10203 12.3115 3.90707Z\" fill=\"#A97B48\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kids Menu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-671ead3 e-flex e-con-boxed e-con e-parent\" data-id=\"671ead3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-71e0dea e-con-full e-flex e-con e-child\" data-id=\"71e0dea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3fbf396 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"3fbf396\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b04efe9 elementor-widget__width-auto elementor-widget-mobile__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b04efe9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\" fill=\"none\"><circle cx=\"6\" cy=\"6\" r=\"5\" stroke=\"#A97B48\" stroke-width=\"2\"><\/circle><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3918176 e-con-full e-flex e-con e-child\" data-id=\"3918176\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b233627 elementor-widget-laptop__width-initial elementor-widget-mobile__width-auto elementor-widget-tablet__width-auto elementor-widget elementor-widget-heading\" data-id=\"b233627\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Kids Menu<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b21ec0 elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8b21ec0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"43\" height=\"38\" viewBox=\"0 0 43 38\" fill=\"none\"><path d=\"M42.11 2.86999C41.99 1.65999 40.89 0.799992 39.71 0.749992C38.84 0.709992 37.88 0.889992 37.05 0.519992C36.48 0.269992 35.71 0.199992 35.09 0.119992C33.8 -0.0400085 32.45 -0.150009 31.25 0.449991C30.48 0.829991 29.75 1.25999 28.97 1.61999C28.54 1.81999 28.15 2.01999 27.66 2.00999C27.24 2.00999 26.83 1.91999 26.42 1.85999C25.6 1.72999 24.78 1.65999 24.04 2.08999C23.29 2.51999 22.83 3.26999 23.12 4.16999C23.4 5.02999 23.43 5.93999 23.46 6.82999C23.48 7.41999 23.53 8.42999 23.01 8.83999C22.44 9.28999 21.94 8.15999 21.7 7.81999C21.51 7.55999 21.33 7.28999 21.14 7.02999C20.8 6.59999 20.28 6.00999 19.67 6.23999C18.97 6.50999 18.83 7.18999 18.73 7.84999C18.62 8.58999 18.45 9.32999 18.42 10.08C18.38 10.86 18.5 11.64 18.5 12.42C18.5 13.35 18.32 14.62 17.74 15.38C17.15 16.15 16.66 16.91 15.55 16.9C14.72 16.9 14.47 15.66 13.68 15.41C13.17 15.25 12.84 15.39 12.67 15.92C12.49 16.48 12.77 17.14 12.86 17.69C12.98 18.41 12.89 19.19 12.69 19.88C11.95 22.47 9.91999 24.26 8.15999 26.18C6.32999 28.18 4.37999 30.12 2.77999 32.31C2.57999 32.58 2.38999 32.84 2.18999 33.11C1.82999 33.59 1.45999 34.07 1.09999 34.56C0.869987 34.88 0.659987 35.2 0.439987 35.53C0.339987 35.68 0.249987 35.83 0.139987 35.97C0.0699869 36.06 -0.0400131 36.17 0.0299869 36.29C0.229987 36.64 0.519987 37.06 0.849987 37.28C0.959987 37.35 1.07999 37.33 1.12999 37.21C1.26999 36.95 1.38999 36.65 1.49999 36.37C1.72999 35.8 2.27999 35.46 2.71999 35.07C3.17999 34.65 3.52999 34.12 3.97999 33.69C5.49999 32.22 7.35999 31.14 8.58999 29.38C9.02999 28.75 9.48999 28.13 9.99999 27.56C10.88 26.56 11.85 25.81 13.05 25.23C13.72 24.91 14.44 24.46 15.21 24.47C16.51 24.49 17.29 25.77 18.52 25.85C20.75 25.99 18.58 23.1 18.18 22.39C17.19 20.62 20.94 21.31 21.57 21.48C22.53 21.74 23.39 22.31 24.32 22.68C25.15 23.01 25.95 23.4 26.79 23.7C27.08 23.8 27.48 23.81 27.78 23.81C28.37 23.81 29.15 23.65 29.46 23.08C29.8 22.45 29.27 21.68 28.91 21.17C28.56 20.67 28.24 20.14 27.87 19.66C27.12 18.68 26.39 17.71 25.79 16.64C25.33 15.83 26.51 15.87 26.96 15.95C27.73 16.08 28.51 16.14 29.29 16.27C30.03 16.39 30.77 16.59 31.52 16.65C32.24 16.71 32.96 16.65 33.66 16.55C34.93 16.38 35.9 15.73 35.7 14.32C35.52 13.02 36.24 12.18 37.46 11.84C38.08 11.67 38.45 11.44 38.96 11.1C39.53 10.72 40.04 10.18 40.3 9.53999C40.48 9.09999 40.35 8.54999 40.59 8.13999C40.77 7.83999 41.14 7.75999 41.35 7.48999C41.95 6.72999 41.99 5.89999 41.85 4.97999C41.74 4.25999 42.17 3.59999 42.1 2.87999L42.11 2.86999ZM38.49 3.97999C37.88 4.68999 36.91 5.15999 36.12 5.65999C35.25 6.21999 34.23 6.61999 33.5 7.35999C33.24 7.61999 32.82 7.96999 32.54 8.20999C33.3 8.34999 34.29 8.36999 35.05 8.26999C35.52 8.20999 36 8.06999 36.48 8.14999C36.72 8.18999 36.94 8.29999 37.18 8.33999C37.34 8.36999 37.71 8.22999 37.75 8.45999C37.56 8.52999 37.18 8.52999 36.98 8.46999C36.16 8.23999 35.55 8.53999 34.75 8.59999C34.12 8.64999 33.48 8.67999 32.84 8.65999C32.19 8.63999 31.52 8.63999 30.96 9.00999C30.27 9.46999 29.68 10.05 29.09 10.62C28.37 11.31 27.61 11.98 26.85 12.62C26.22 13.15 25.47 13.62 24.82 14.17C24.91 14.15 25 14.13 25.08 14.11C26.19 13.85 27.31 13.84 28.34 13.27C28.96 12.93 29.86 13.37 30.44 13.65C30.98 13.91 31.56 14.08 32.15 14.21C32.42 14.27 32.7 14.28 32.97 14.32C33.01 14.32 33.62 14.51 33.35 14.56C33.19 14.59 32.82 14.49 32.76 14.48C32.44 14.44 32.12 14.46 31.81 14.4C31.37 14.33 30.96 14.26 30.55 14.09C30.06 13.89 29.55 13.67 29.01 13.65C28.37 13.63 27.86 13.97 27.27 14.14C26.74 14.29 26.2 14.38 25.66 14.47C24.34 14.7 22.97 15.53 21.86 16.27C21.03 16.82 20.23 17.45 19.47 18.1C18.74 18.72 18.11 19.44 17.39 20.07C17.56 20.07 17.74 20.07 17.92 20.05C18.42 20 18.96 19.88 19.47 19.8C20.09 19.7 20.81 19.74 21.41 19.57C23.55 18.97 25.36 20.94 27.15 21.76C27.27 21.82 27.19 21.99 27.07 21.94C25.36 21.36 23.48 19.37 21.55 19.95C21.16 20.07 20.82 20.05 20.41 20.07C19.95 20.09 19.5 20.23 19.05 20.27C18.61 20.32 18.21 20.45 17.77 20.49C16.76 20.59 15.96 21.24 15.16 21.78C14.33 22.34 13.72 23.16 12.92 23.76C11.95 24.49 11.03 25.29 10.18 26.17C9.85999 26.5 9.60999 26.9 9.26999 27.21C8.81999 27.6 8.38999 27.98 7.96999 28.4C7.19999 29.18 6.44999 29.96 5.71999 30.79C5.05999 31.55 4.42999 32.35 3.71999 33.07C3.40999 33.39 3.00999 33.53 2.70999 33.88C2.33999 34.32 1.96999 34.77 1.59999 35.21C1.51999 35.31 1.35999 35.18 1.43999 35.08C1.96999 34.4 2.50999 33.38 3.27999 32.94C3.69999 32.7 4.04999 32.08 4.36999 31.72C4.71999 31.33 5.04999 30.92 5.41999 30.55C6.17999 29.77 6.89999 28.95 7.67999 28.17C8.42999 27.42 9.13999 26.68 9.84999 25.9C10.56 25.11 11.38 24.42 12.2 23.75C12.91 23.18 13.56 22.57 14.25 21.98C15.02 21.33 15.86 20.75 16.66 20.13C17.86 19.21 18.62 17.85 19.06 16.41C19.23 15.85 19.5 15.33 19.68 14.76C19.9 14.05 20.43 13.36 20.42 12.58C20.42 12.17 20.15 12.11 20.04 11.77C19.93 11.45 20.07 11.17 20.09 10.83C20.11 10.47 20.21 10.13 20.21 9.76999C20.21 9.48999 20.12 9.17999 20.09 8.89999C20.03 8.41999 19.77 8.07999 19.91 7.59999C19.94 7.49999 20.12 7.54999 20.09 7.64999C19.97 8.11999 20.31 8.80999 20.4 9.29999C20.49 9.85999 20.45 10.31 20.4 10.87C20.35 11.43 20.64 11.69 20.79 12.17C20.92 12.57 20.61 13.02 20.48 13.39C20.08 14.55 19.47 15.66 19.23 16.87C19.12 17.42 18.83 17.88 18.57 18.36C18.66 18.28 18.74 18.2 18.83 18.12C19.57 17.44 20.32 16.69 21.13 16.09C21.95 15.48 22.88 15.05 23.69 14.42C24.22 14.01 24.75 13.32 25.01 12.7C25.17 12.32 25.42 12.03 25.5 11.61C25.58 11.19 25.53 10.72 25.5 10.29C25.44 9.08999 25.49 7.60999 26.22 6.60999C26.27 6.53999 26.38 6.60999 26.35 6.68999C26.04 7.41999 25.94 8.06999 25.89 8.85999C25.83 9.66999 26.04 10.43 26.02 11.23C26 11.85 25.89 12.29 25.47 12.74C25.28 12.95 25.11 13.2 24.94 13.44C25.67 12.88 26.4 12.33 27.13 11.77C27.49 11.49 27.84 11.21 28.19 10.92C29.4 9.91999 30.34 8.47999 30.61 6.90999C30.8 5.80999 31.46 4.78999 32.32 4.09999C32.35 4.06999 32.41 4.11999 32.38 4.14999C32.11 4.62999 31.74 5.05999 31.48 5.54999C31.12 6.22999 31.09 6.99999 30.87 7.71999C30.71 8.24999 30.41 8.82999 30.04 9.33999C30.39 9.04999 30.75 8.76999 31.13 8.49999C31.53 8.21999 31.97 7.99999 32.38 7.72999C32.76 7.46999 33.07 7.12999 33.43 6.84999C34.23 6.22999 35.09 5.69999 35.97 5.20999C36.74 4.77999 37.73 4.43999 38.37 3.80999C38.45 3.72999 38.6 3.83999 38.52 3.92999L38.49 3.97999Z\" fill=\"#A97B48\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f6d95f e-con-full e-flex e-con e-child\" data-id=\"9f6d95f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-86f7761 e-con-full e-flex e-con e-child\" data-id=\"86f7761\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2025d7 elementor-grid-1 elementor-grid-tablet-1 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"a2025d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:22500,&quot;columns&quot;:1,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;columns_tablet&quot;:1,&quot;_skin&quot;:&quot;post&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-22500\">.elementor-22500 .elementor-element.elementor-element-93d84a8{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:flex-start;--gap:12px 12px;--row-gap:12px;--column-gap:12px;--margin-top:0px;--margin-bottom:0px;--margin-left:0px;--margin-right:0px;--padding-top:0px;--padding-bottom:24px;--padding-left:0px;--padding-right:0px;}.elementor-22500 .elementor-element.elementor-element-93d84a8.e-con{--align-self:flex-start;}.elementor-22500 .elementor-element.elementor-element-5ea2606{--display:flex;--gap:0px 0px;--row-gap:0px;--column-gap:0px;border-style:solid;--border-style:solid;border-width:0px 0px 0px 0px;--border-top-width:0px;--border-right-width:0px;--border-bottom-width:0px;--border-left-width:0px;border-color:#E8DED30F;--border-color:#E8DED30F;--margin-top:0px;--margin-bottom:0px;--margin-left:0px;--margin-right:0px;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-22500 .elementor-element.elementor-element-bd900ec .elementor-heading-title{font-family:\"Raleway\", Sans-serif;font-size:24px;font-weight:bold;line-height:20px;}.elementor-22500 .elementor-element.elementor-element-bd900ec > .elementor-widget-container{margin:0px 0px 8px 0px;padding:0px 0px 0px 0px;}.elementor-22500 .elementor-element.elementor-element-4d85114 .elementor-heading-title{font-family:\"Lora\", Sans-serif;font-size:16px;font-weight:400;line-height:20px;}.elementor-22500 .elementor-element.elementor-element-4d85114 > .elementor-widget-container{margin:0px 0px 0px 0px;padding:0px 0px 0px 0px;}@media(max-width:1024px){.elementor-22500 .elementor-element.elementor-element-bd900ec .elementor-heading-title{font-size:32px;line-height:32px;}}@media(min-width:768px){.elementor-22500 .elementor-element.elementor-element-93d84a8{--width:100%;}}@media(max-width:767px){.elementor-22500 .elementor-element.elementor-element-93d84a8{--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:space-between;--align-items:flex-start;--margin-top:0px;--margin-bottom:0px;--margin-left:0px;--margin-right:0px;--padding-top:0px;--padding-bottom:24px;--padding-left:0px;--padding-right:0px;}.elementor-22500 .elementor-element.elementor-element-93d84a8.e-con{--order:-99999 \/* order start hack *\/;}.elementor-22500 .elementor-element.elementor-element-5ea2606{--gap:0px 0px;--row-gap:0px;--column-gap:0px;border-width:0px 0px 1px 0px;--border-top-width:0px;--border-right-width:0px;--border-bottom-width:1px;--border-left-width:0px;--border-radius:0px 0px 0px 0px;--margin-top:0px;--margin-bottom:0px;--margin-left:0px;--margin-right:0px;--padding-top:0px;--padding-bottom:12px;--padding-left:0px;--padding-right:0px;}.elementor-22500 .elementor-element.elementor-element-bd900ec .elementor-heading-title{font-size:20px;line-height:20px;}.elementor-22500 .elementor-element.elementor-element-bd900ec > .elementor-widget-container{margin:0px 0px 0px 0px;padding:0px 0px 0px 0px;}.elementor-22500 .elementor-element.elementor-element-4d85114 .elementor-heading-title{line-height:16px;}.elementor-22500 .elementor-element.elementor-element-4d85114 > .elementor-widget-container{margin:0px 0px 0px 0px;padding:0px 0px 0px 0px;}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"22500\" class=\"elementor elementor-22500 elementor-10039 e-loop-item e-loop-item-23681 post-23681 menu-items type-menu-items status-publish hentry menu-categories-kids\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-93d84a8 e-con-full e-flex e-con e-parent\" data-id=\"93d84a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5ea2606 e-con-full e-flex e-con e-child\" data-id=\"5ea2606\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd900ec elementor-widget elementor-widget-heading\" data-id=\"bd900ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Half baby back ribs<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d85114 elementor-widget elementor-widget-heading\" data-id=\"4d85114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Served with a choice of side dish between fries, garlic mashed potatoes, plain baked potato or steamed vegetables.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"22500\" class=\"elementor elementor-22500 elementor-10039 e-loop-item e-loop-item-23682 post-23682 menu-items type-menu-items status-publish hentry menu-categories-kids\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-93d84a8 e-con-full e-flex e-con e-parent\" data-id=\"93d84a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5ea2606 e-con-full e-flex e-con e-child\" data-id=\"5ea2606\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd900ec elementor-widget elementor-widget-heading\" data-id=\"bd900ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Chicken tenders (3)<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d85114 elementor-widget elementor-widget-heading\" data-id=\"4d85114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Served with a choice of side dish between fries, garlic mashed potatoes, plain baked potato or steamed vegetables.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"22500\" class=\"elementor elementor-22500 elementor-10039 e-loop-item e-loop-item-23683 post-23683 menu-items type-menu-items status-publish hentry menu-categories-kids\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-93d84a8 e-con-full e-flex e-con e-parent\" data-id=\"93d84a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5ea2606 e-con-full e-flex e-con e-child\" data-id=\"5ea2606\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd900ec elementor-widget elementor-widget-heading\" data-id=\"bd900ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Grilled chicken<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d85114 elementor-widget elementor-widget-heading\" data-id=\"4d85114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Served with a choice of side dish between fries, garlic mashed potatoes, plain baked potato or steamed vegetables.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"22500\" class=\"elementor elementor-22500 elementor-10039 e-loop-item e-loop-item-23680 post-23680 menu-items type-menu-items status-publish hentry menu-categories-kids\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-93d84a8 e-con-full e-flex e-con e-parent\" data-id=\"93d84a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5ea2606 e-con-full e-flex e-con e-child\" data-id=\"5ea2606\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd900ec elementor-widget elementor-widget-heading\" data-id=\"bd900ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Linguini marinara<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"22500\" class=\"elementor elementor-22500 elementor-10039 e-loop-item e-loop-item-26845 post-26845 menu-items type-menu-items status-publish hentry menu-categories-kids\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-93d84a8 e-con-full e-flex e-con e-parent\" data-id=\"93d84a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5ea2606 e-con-full e-flex e-con e-child\" data-id=\"5ea2606\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd900ec elementor-widget elementor-widget-heading\" data-id=\"bd900ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Classic Burger<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d85114 elementor-widget elementor-widget-heading\" data-id=\"4d85114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Served with a choice of side dish between fries, garlic mashed potatoes, plain baked potato or steamed vegetables.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a401eb e-con-full e-flex e-con e-child\" data-id=\"7a401eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ddb04a elementor-widget elementor-widget-image\" data-id=\"8ddb04a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"569\" height=\"560\" src=\"https:\/\/madisonsresto.com\/wp-content\/uploads\/2024\/08\/Enfant_new.webp\" class=\"attachment-full size-full wp-image-21456\" alt=\"\" srcset=\"https:\/\/madisonsresto.com\/wp-content\/uploads\/2024\/08\/Enfant_new.webp 569w, https:\/\/madisonsresto.com\/wp-content\/uploads\/2024\/08\/Enfant_new-300x295.webp 300w\" sizes=\"(max-width: 569px) 100vw, 569px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c78e1b e-flex e-con-boxed e-con e-parent\" data-id=\"7c78e1b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c146f19 elementor-widget elementor-widget-spacer\" data-id=\"c146f19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Return to main menu Kids Menu Menu Principal Menu Dessert Menu de Bar Menu de Vin Menu Enfants Menu Principal Menu Dessert Menu de Bar Menu de Vin Menu Enfants Go back Dessert Menu Lunch Menu Bar Menu Wine Menu Kids Menu Kids Menu<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22521","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/madisonsresto.com\/en\/wp-json\/wp\/v2\/pages\/22521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madisonsresto.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/madisonsresto.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/madisonsresto.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/madisonsresto.com\/en\/wp-json\/wp\/v2\/comments?post=22521"}],"version-history":[{"count":5,"href":"https:\/\/madisonsresto.com\/en\/wp-json\/wp\/v2\/pages\/22521\/revisions"}],"predecessor-version":[{"id":27326,"href":"https:\/\/madisonsresto.com\/en\/wp-json\/wp\/v2\/pages\/22521\/revisions\/27326"}],"wp:attachment":[{"href":"https:\/\/madisonsresto.com\/en\/wp-json\/wp\/v2\/media?parent=22521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}